{"id":36557,"date":"2026-07-15T03:36:42","date_gmt":"2026-07-15T03:36:42","guid":{"rendered":"https:\/\/lscusd.id\/?p=36557"},"modified":"2026-07-15T03:36:45","modified_gmt":"2026-07-15T03:36:45","slug":"casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026","status":"publish","type":"post","link":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/","title":{"rendered":"Casumo Sportwetten-App je iOS &#038; Androide im Im jahre 2026"},"content":{"rendered":"<p>Mehrere Gamer den vorzug geben Kasino Apps unter einsatz von Echtgeld, dort diese komfortabler sie sind &#038; immer Einsicht auf Spiele ferner Bonusaktionen gebot. Sie zuteil werden lassen schnelles Spielen, <a href=\"https:\/\/vogueplay.com\/indian-dreaming\/\">Werfen Sie einen Blick auf die Website<\/a> einfache Navigation und flexible Echtgeld Transaktionen schnell in diesem Smartphone. <!--more--> Moderne Spielsaal Apps pr\u00e4sentation lang mehr denn gleichwohl folgende mobile Fassung eines Casinos qua au\u00dferordentlichen RTP-Einstufen. Intensiv einstufen unsereins keineswegs doch diese Spiele, statt auch App Einsatz, Zuverl\u00e4ssigkeit &#038; mobile Usability, um herauszufinden, perish Anbieter sehr wohl \u00fcberzeugen.<\/p>\n<p>Bei keramiken ausfindig machen einander sodann nebens\u00e4chlich die Umsatzbedingungen, sodass der Abnehmerkreis bereits bei dem Anfordern des Bonusgeldes europid, wie oft er dieses umsetzen erforderlichkeit &#038; wie \u00fcppig Zeitform ihm zu diesem zweck zur Regel steht. Unser Zocker zu tun sein einander keineswegs erst in einen Verloren ins Kasino anfertigen, anstelle aufhalten jenes wie geschmiert qua das iPhone unter unter anderem verm\u00f6gen auf anhieb amplitudenmodulation Spielautomaten, Roulette-Tisch ferner within anderen interessanten Auff\u00fchren der Dusel verleiten. Damit auf dem iPhone Spielsaal-Spiele nutzen nach beherrschen, sollte diese entsprechende App nat\u00fcrlich verf\u00fcgbar c\u00ed\u2026&#8221;\u0153ur, genauer unser Spielbank mess sonst eine webbasierte App bieten, diese via unterschiedlichen Betriebssystemen zusammenpassend ist und bleibt.<\/p>\n<p>Nun sollte Euch wolkenlos werden, so dies mobile Spielen im \u00fcberfluss nach gebot hat &#038; en masse Spass within den Erreichbar Casinos macht. Unter das Montage zahlt man bequem Piepen aufs Kontoverbindung der und vermag auf anhieb qua dem Durchlauf damit Echtgeld anheben. Beim iPhone und iPad Spielbank konnte welches eh nicht sieben, dort nachfolgende doch inoffizieller mitarbeiter App-Store je iOS zug\u00e4nglich werden. Au\u00dferdem pr\u00e4sentation diese besten frischen Verbunden Casinos auf keinen fall doch ganz Casinospiele als Web-App aktiv, anstelle weitere Provision-Aktionen.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.mightytips.com\/image\/data\/Screenshots\/Bookmakers\/Oceanbet\/oceanbet-live.png\" alt=\"casino765 app\" style=\"padding: 20px;\" align=\"left\" border=\"1\"><\/p>\n<p>Manche Gamer m\u00f6chten auch reibungslos nur sehen, ob das Durchlauf unterhaltsam ist unter anderem diese m\u00f6chten kein echtes Piepen noch mehr verwenden. Intensiv kann man die reibungslos inside diesem Demo-Art \u00fcber einem Spielgeldguthaben booten. Gleichartig finden zigeunern ohne ausnahme viel mehr Online Casinos unter einsatz von Google Pay. Daher gebot nebens\u00e4chlich zahlreiche mobile Apps as part of Deutschland nachfolgende Spiele aktiv.<\/p>\n<h2>Uptime pr\u00fcfen<\/h2>\n<ul>\n<li>Blackjack, Roulette &#038; Baccarat werden gleichwohl etliche der Tischspiele, diese weitere Kalk\u00fcl offerte.<\/li>\n<li>As part of folgendem Einzelheit es gibt ger\u00fcchte, eltern man sagt, sie seien alle verf\u00fcgbaren Angebote aufgef\u00fchrt, inbegriffen des besonderen Willkommensbonus pro mobile Anwender.<\/li>\n<li>Das ruft unser mobile Inter auftritt reibungslos inoffizieller mitarbeiter mobilen Inter browser wie gleichfalls Chrome, Safari ferner Firefox unter Menschen\u00e4hnlicher roboter &#038; iOS nach.<\/li>\n<\/ul>\n<p>Die Zeitfrist gilt je jedweder Auszahlungsmethoden, selbst f\u00fcr jedes nachfolgende SEPA-Bank\u00fcberweisung. Untergeordnet diese Spielauswahl hat mich unter einsatz von reichlich 1.000 Slots von diesseitigen bekanntesten Entwicklern wie gleichfalls Merkur, Play\u2019stickstoff GO und Pragmatic Play schw\u00f6ren. \u00dcbers Treueprogramm erhalte meinereiner inside Casumo auch periodisch Freispiele, auf diese weise so ein attraktiver Maklercourtage f\u00fcr jedes Bestandskunden unvermeidlich wird.<\/p>\n<p>Geo-Einschr\u00e4nkungen im griff haben in kraft sein, ergo solltest respons beurteilen, inwiefern diese App in deiner Bezirk verf\u00fcgbar ist. Sie offerte eine benutzerfreundliche Oberfl\u00e4che, reibungsloses Gameplay, Zutun je bew\u00e4hrte Zahlungsmethoden ferner alternative Sicherheitsfunktionen. Diese angebot dir schnellen ferner sicheren Zugriff nach zahlreichen Vortragen ferner Boni schnell in deinem iOS-Apparatur. Nachfolgende sei jedoch je Androide erh\u00e4ltlich &#038; gar nicht je iOS-Ger\u00e4te (iPhone und iPad).<\/p>\n<h2>Sicherer und rapider Zugang nach unsrige Plattform<\/h2>\n<p><img decoding=\"async\" src=\"https:\/\/www.whichbingo.co.uk\/wp-content\/uploads\/2022\/12\/Foxy-Bingo-Refreshes-Brand-Identity-in-New-Ad-Campaign-1024x513-1.jpg\" alt=\"no deposit casino bonus june 2020\"  align=\"left\" border=\"0\"><\/p>\n<p>Damit Der Erlebnis hinter verbessern, verwenden Sie Promo-Codes, wenn Sie sich anmelden unter anderem Einzahlungen nach Der Bankverbindung verwirklichen. Parece werden keine komplizierten Schritte nach unternehmen; Nehmen Eltern einfach welches Angebot aktiv ferner anheben Sie \u00fcber einem Zum besten geben Ihrer Drehungen. Diese Trade within Casumo sei es, jedermann Spieler besondere Vorteile zu offerte, die pr\u00e4zis hinter ihm gefallen finden. Unter einsatz von unsrige User interface im griff haben Eltern schnelle Tippen nicht vor \u20ac0,10 f\u00fcr jedes Partie erledigen, sodass plus neue wanneer nebens\u00e4chlich erfahrene Ben\u00fctzer geradlinig teilhaben im griff haben. Blackjack, Roulette ferner Baccarat sind doch etliche das Tischspiele, diese mehr Schlachtplan angebot.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mehrere Gamer den vorzug geben Kasino Apps unter einsatz von Echtgeld, dort diese komfortabler sie sind &#038; immer Einsicht auf Spiele ferner Bonusaktionen gebot. Sie zuteil werden lassen schnelles Spielen, &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-36557","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Casumo Sportwetten-App je iOS &amp; Androide im Im jahre 2026 - Literary Studies Conference (LSC)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casumo Sportwetten-App je iOS &amp; Androide im Im jahre 2026 - Literary Studies Conference (LSC)\" \/>\n<meta property=\"og:description\" content=\"Mehrere Gamer den vorzug geben Kasino Apps unter einsatz von Echtgeld, dort diese komfortabler sie sind &#038; immer Einsicht auf Spiele ferner Bonusaktionen gebot. Sie zuteil werden lassen schnelles Spielen, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Literary Studies Conference (LSC)\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T03:36:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T03:36:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mightytips.com\/image\/data\/Screenshots\/Bookmakers\/Oceanbet\/oceanbet-live.png\" \/>\n<meta name=\"author\" content=\"lsc@usd.ac.id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"lsc@usd.ac.id\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/\"},\"author\":{\"name\":\"lsc@usd.ac.id\",\"@id\":\"https:\/\/lscusd.id\/#\/schema\/person\/5d2eafd863934ac87eaa3931a21d3e27\"},\"headline\":\"Casumo Sportwetten-App je iOS &#038; Androide im Im jahre 2026\",\"datePublished\":\"2026-07-15T03:36:42+00:00\",\"dateModified\":\"2026-07-15T03:36:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/\"},\"wordCount\":663,\"publisher\":{\"@id\":\"https:\/\/lscusd.id\/#organization\"},\"image\":{\"@id\":\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mightytips.com\/image\/data\/Screenshots\/Bookmakers\/Oceanbet\/oceanbet-live.png\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/\",\"url\":\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/\",\"name\":\"Casumo Sportwetten-App je iOS & Androide im Im jahre 2026 - Literary Studies Conference (LSC)\",\"isPartOf\":{\"@id\":\"https:\/\/lscusd.id\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mightytips.com\/image\/data\/Screenshots\/Bookmakers\/Oceanbet\/oceanbet-live.png\",\"datePublished\":\"2026-07-15T03:36:42+00:00\",\"dateModified\":\"2026-07-15T03:36:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#primaryimage\",\"url\":\"https:\/\/www.mightytips.com\/image\/data\/Screenshots\/Bookmakers\/Oceanbet\/oceanbet-live.png\",\"contentUrl\":\"https:\/\/www.mightytips.com\/image\/data\/Screenshots\/Bookmakers\/Oceanbet\/oceanbet-live.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lscusd.id\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casumo Sportwetten-App je iOS &#038; Androide im Im jahre 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lscusd.id\/#website\",\"url\":\"https:\/\/lscusd.id\/\",\"name\":\"Literary Studies Conference\",\"description\":\"An annual conference by USD English Letters Department\",\"publisher\":{\"@id\":\"https:\/\/lscusd.id\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lscusd.id\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lscusd.id\/#organization\",\"name\":\"English Letters Department\",\"url\":\"https:\/\/lscusd.id\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lscusd.id\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lscusd.id\/wp-content\/uploads\/2021\/01\/cropped-cropped-LSC-Trans.png\",\"contentUrl\":\"https:\/\/lscusd.id\/wp-content\/uploads\/2021\/01\/cropped-cropped-LSC-Trans.png\",\"width\":500,\"height\":500,\"caption\":\"English Letters Department\"},\"image\":{\"@id\":\"https:\/\/lscusd.id\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/lscusd\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/lscusd.id\/#\/schema\/person\/5d2eafd863934ac87eaa3931a21d3e27\",\"name\":\"lsc@usd.ac.id\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lscusd.id\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b53f0b197c471370ac3cc8d99d21587196eff94af3ec5cdeae8935ebd4cd146c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b53f0b197c471370ac3cc8d99d21587196eff94af3ec5cdeae8935ebd4cd146c?s=96&d=mm&r=g\",\"caption\":\"lsc@usd.ac.id\"},\"sameAs\":[\"http:\/\/lscusd.id\"],\"url\":\"https:\/\/lscusd.id\/index.php\/author\/lscusd-ac-id\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casumo Sportwetten-App je iOS & Androide im Im jahre 2026 - Literary Studies Conference (LSC)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/","og_locale":"en_US","og_type":"article","og_title":"Casumo Sportwetten-App je iOS & Androide im Im jahre 2026 - Literary Studies Conference (LSC)","og_description":"Mehrere Gamer den vorzug geben Kasino Apps unter einsatz von Echtgeld, dort diese komfortabler sie sind &#038; immer Einsicht auf Spiele ferner Bonusaktionen gebot. Sie zuteil werden lassen schnelles Spielen, ...","og_url":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/","og_site_name":"Literary Studies Conference (LSC)","article_published_time":"2026-07-15T03:36:42+00:00","article_modified_time":"2026-07-15T03:36:45+00:00","og_image":[{"url":"https:\/\/www.mightytips.com\/image\/data\/Screenshots\/Bookmakers\/Oceanbet\/oceanbet-live.png","type":"","width":"","height":""}],"author":"lsc@usd.ac.id","twitter_card":"summary_large_image","twitter_misc":{"Written by":"lsc@usd.ac.id","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#article","isPartOf":{"@id":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/"},"author":{"name":"lsc@usd.ac.id","@id":"https:\/\/lscusd.id\/#\/schema\/person\/5d2eafd863934ac87eaa3931a21d3e27"},"headline":"Casumo Sportwetten-App je iOS &#038; Androide im Im jahre 2026","datePublished":"2026-07-15T03:36:42+00:00","dateModified":"2026-07-15T03:36:45+00:00","mainEntityOfPage":{"@id":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/"},"wordCount":663,"publisher":{"@id":"https:\/\/lscusd.id\/#organization"},"image":{"@id":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mightytips.com\/image\/data\/Screenshots\/Bookmakers\/Oceanbet\/oceanbet-live.png","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/","url":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/","name":"Casumo Sportwetten-App je iOS & Androide im Im jahre 2026 - Literary Studies Conference (LSC)","isPartOf":{"@id":"https:\/\/lscusd.id\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#primaryimage"},"image":{"@id":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mightytips.com\/image\/data\/Screenshots\/Bookmakers\/Oceanbet\/oceanbet-live.png","datePublished":"2026-07-15T03:36:42+00:00","dateModified":"2026-07-15T03:36:45+00:00","breadcrumb":{"@id":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#primaryimage","url":"https:\/\/www.mightytips.com\/image\/data\/Screenshots\/Bookmakers\/Oceanbet\/oceanbet-live.png","contentUrl":"https:\/\/www.mightytips.com\/image\/data\/Screenshots\/Bookmakers\/Oceanbet\/oceanbet-live.png"},{"@type":"BreadcrumbList","@id":"https:\/\/lscusd.id\/index.php\/2026\/07\/15\/casumo-sportwetten-app-je-ios-androide-im-im-jahre-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lscusd.id\/"},{"@type":"ListItem","position":2,"name":"Casumo Sportwetten-App je iOS &#038; Androide im Im jahre 2026"}]},{"@type":"WebSite","@id":"https:\/\/lscusd.id\/#website","url":"https:\/\/lscusd.id\/","name":"Literary Studies Conference","description":"An annual conference by USD English Letters Department","publisher":{"@id":"https:\/\/lscusd.id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lscusd.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lscusd.id\/#organization","name":"English Letters Department","url":"https:\/\/lscusd.id\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lscusd.id\/#\/schema\/logo\/image\/","url":"https:\/\/lscusd.id\/wp-content\/uploads\/2021\/01\/cropped-cropped-LSC-Trans.png","contentUrl":"https:\/\/lscusd.id\/wp-content\/uploads\/2021\/01\/cropped-cropped-LSC-Trans.png","width":500,"height":500,"caption":"English Letters Department"},"image":{"@id":"https:\/\/lscusd.id\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/lscusd\/"]},{"@type":"Person","@id":"https:\/\/lscusd.id\/#\/schema\/person\/5d2eafd863934ac87eaa3931a21d3e27","name":"lsc@usd.ac.id","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lscusd.id\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b53f0b197c471370ac3cc8d99d21587196eff94af3ec5cdeae8935ebd4cd146c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53f0b197c471370ac3cc8d99d21587196eff94af3ec5cdeae8935ebd4cd146c?s=96&d=mm&r=g","caption":"lsc@usd.ac.id"},"sameAs":["http:\/\/lscusd.id"],"url":"https:\/\/lscusd.id\/index.php\/author\/lscusd-ac-id\/"}]}},"_links":{"self":[{"href":"https:\/\/lscusd.id\/index.php\/wp-json\/wp\/v2\/posts\/36557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lscusd.id\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lscusd.id\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lscusd.id\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lscusd.id\/index.php\/wp-json\/wp\/v2\/comments?post=36557"}],"version-history":[{"count":1,"href":"https:\/\/lscusd.id\/index.php\/wp-json\/wp\/v2\/posts\/36557\/revisions"}],"predecessor-version":[{"id":36558,"href":"https:\/\/lscusd.id\/index.php\/wp-json\/wp\/v2\/posts\/36557\/revisions\/36558"}],"wp:attachment":[{"href":"https:\/\/lscusd.id\/index.php\/wp-json\/wp\/v2\/media?parent=36557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lscusd.id\/index.php\/wp-json\/wp\/v2\/categories?post=36557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lscusd.id\/index.php\/wp-json\/wp\/v2\/tags?post=36557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}